{"id":3021,"date":"2016-07-14T11:55:00","date_gmt":"2016-07-14T11:55:00","guid":{"rendered":"https:\/\/puntes.es\/?p=3021"},"modified":"2021-08-05T11:11:26","modified_gmt":"2021-08-05T11:11:26","slug":"drupa-2016","status":"publish","type":"post","link":"https:\/\/puntes.es\/fr\/drupa-2016\/","title":{"rendered":"Drupa 2016"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie. 17 pavillons remplis d\u2019innovations techniques et un public bel et bien pr\u00e9sent, venu du monde entier pour y assister.<br>Il n\u2019est pas possible de tout voir en 3 jours, nous avons donc du cibler nos visites et se concentrer sur les derniers d\u00e9veloppements de la flexographie, les applications de gestion des flux et les outils de contr\u00f4le des couleurs.<br>La flexo a r\u00e9alis\u00e9 de grand progr\u00e8s ces derni\u00e8res ann\u00e9es et continu de progresser pour atteindre une qualit\u00e9 d\u2019impression qui rivalise avec l\u2019offset et l\u2019h\u00e9lio.<br>Comexi pr\u00e9sentait sur son stand son concept de l\u2019industrie 4.0, avec des robots compl\u00e9mentaires \u00e0 l\u2019imprimeuse qui g\u00e8rent les changements de manchons et de c\u00e9ramiques de mani\u00e8re automatique obtenant des changements rapides et s\u00e9curis\u00e9s.<br>Avec les m\u00eames objectifs de s\u00e9curit\u00e9 pour l\u2019op\u00e9rateur et de diminution des temps de changement, Bobst pr\u00e9sentait ses nouveaut\u00e9s en services de maintenance et d\u2019aide en ligne. Tout comme pour Label expo, ils exposaient, entre autres, la flexo digital M6, une imprimeuse petite laize configur\u00e9e en heptachromie augmentant ainsi le gamut des couleurs et pouvant r\u00e9aliser des changements de clich\u00e9s pour le prochain d\u00e9cor alors que la machine est en train d\u2019imprimer, adieu les temps morts.<br>Avec son mod\u00e8le Miraflex CL10 et ses diff\u00e9rents modules int\u00e9gr\u00e9s Windm\u00f6ller &amp; Holscher exposait le haut niveau d\u2019efficacit\u00e9 et la maniabilit\u00e9 simple et intuitive de sa nouvelle g\u00e9n\u00e9ration de machine.<br>Nous nous sommes rapproch\u00e9s aussi du stand de Soma o\u00f9 nous avons vus son nouveau mod\u00e8le Optima pour moyenne laize exposant les diff\u00e9rents avantages de leurs machines comme le syst\u00e8me d\u2019\u00e9limination des vibrations par exemple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esko, X-rite et Pantone se trouvent d\u00e9sormais sur le m\u00eame stand ce qui permet une synergie de groupe au niveau des technologies de communication, formulation, mesures et gestion des couleurs. Nous avons r\u00e9alis\u00e9 avec eux une d\u00e9monstration des derni\u00e8res nouveaut\u00e9s et avons d\u00e9couvert leur derniere ligne : laser, insoleuse et table de coupe dirig\u00e9es fondamentalement \u00e0 l\u2019automatisation et la stabilit\u00e9 de notre process de production.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de visiter le salon, nous nous sommes \u00e9galement rendus \u00e0 la remise des prix Diamand organis\u00e9 par FTA Europe, l\u2019association Europ\u00e9enne de la flexographie. Les gagnants Gold de chaque association nationale se retrouvaient de nouveau en comp\u00e9tition au niveau Europ\u00e9en pour obtenir la r\u00e9compense supr\u00eame dans chacune des cat\u00e9gories. Un des mod\u00e8les pour lequel nous avons r\u00e9alis\u00e9 la pr\u00e9-presse et imprim\u00e9 par notre client Belge qui avait d\u00e9j\u00e0 remport\u00e9 le prix Gold avec son association Nationale a remport\u00e9 la seconde place dans sa cat\u00e9gorie en impression sur film-laize moyenne. C\u2019\u00e9tait pour nous la reconnaissance d\u2019un travail collectif et nous en profitons \u00e9galement pour f\u00e9liciter \u00e0 tous les nomin\u00e9s pour le haut niveau de qualit\u00e9 dont ils ont su faire preuve.<br>Tout ceci nous confirme que la flexo se porte bien, et prouve qu\u2019elle reste une alternative de choix pour la r\u00e9alisation des emballages.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie. 17 pavillons remplis d\u2019innovations techniques et un public bel et bien pr\u00e9sent, venu du monde entier pour y assister.Il n\u2019est pas possible de tout voir en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,24],"tags":[],"class_list":["post-3021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drupa 2016 - Puntes<\/title>\n<meta name=\"description\" content=\"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puntes.es\/fr\/drupa-2016\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drupa 2016 - Puntes\" \/>\n<meta property=\"og:description\" content=\"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puntes.es\/fr\/drupa-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Puntes\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-14T11:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-05T11:11:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AgenciaESI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AgenciaESI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/\"},\"author\":{\"name\":\"AgenciaESI\",\"@id\":\"https:\\\/\\\/puntes.es\\\/#\\\/schema\\\/person\\\/4a8046f9f021d0bcd1f32edb26c1b11d\"},\"headline\":\"Drupa 2016\",\"datePublished\":\"2016-07-14T11:55:00+00:00\",\"dateModified\":\"2021-08-05T11:11:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/\"},\"wordCount\":569,\"publisher\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/drupa-20161-1.jpg\",\"articleSection\":[\"\u00c9v\u00e9nements\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/\",\"url\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/\",\"name\":\"Drupa 2016 - Puntes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/drupa-20161-1.jpg\",\"datePublished\":\"2016-07-14T11:55:00+00:00\",\"dateModified\":\"2021-08-05T11:11:26+00:00\",\"description\":\"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/drupa-20161-1.jpg\",\"contentUrl\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/drupa-20161-1.jpg\",\"width\":700,\"height\":644},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/puntes.es\\\/fr\\\/drupa-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/puntes.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drupa 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/puntes.es\\\/#website\",\"url\":\"https:\\\/\\\/puntes.es\\\/\",\"name\":\"Puntes\",\"description\":\"Packaging partners\",\"publisher\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/puntes.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/puntes.es\\\/#organization\",\"name\":\"Puntes\",\"url\":\"https:\\\/\\\/puntes.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/puntes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/punts.svg\",\"contentUrl\":\"https:\\\/\\\/puntes.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/punts.svg\",\"width\":1,\"height\":1,\"caption\":\"Puntes\"},\"image\":{\"@id\":\"https:\\\/\\\/puntes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/puntes.es\\\/#\\\/schema\\\/person\\\/4a8046f9f021d0bcd1f32edb26c1b11d\",\"name\":\"AgenciaESI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g\",\"caption\":\"AgenciaESI\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drupa 2016 - Puntes","description":"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puntes.es\/fr\/drupa-2016\/","og_locale":"fr_FR","og_type":"article","og_title":"Drupa 2016 - Puntes","og_description":"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.","og_url":"https:\/\/puntes.es\/fr\/drupa-2016\/","og_site_name":"Puntes","article_published_time":"2016-07-14T11:55:00+00:00","article_modified_time":"2021-08-05T11:11:26+00:00","og_image":[{"width":700,"height":644,"url":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg","type":"image\/jpeg"}],"author":"AgenciaESI","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"AgenciaESI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#article","isPartOf":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/"},"author":{"name":"AgenciaESI","@id":"https:\/\/puntes.es\/#\/schema\/person\/4a8046f9f021d0bcd1f32edb26c1b11d"},"headline":"Drupa 2016","datePublished":"2016-07-14T11:55:00+00:00","dateModified":"2021-08-05T11:11:26+00:00","mainEntityOfPage":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/"},"wordCount":569,"publisher":{"@id":"https:\/\/puntes.es\/#organization"},"image":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg","articleSection":["\u00c9v\u00e9nements","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/puntes.es\/fr\/drupa-2016\/","url":"https:\/\/puntes.es\/fr\/drupa-2016\/","name":"Drupa 2016 - Puntes","isPartOf":{"@id":"https:\/\/puntes.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#primaryimage"},"image":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg","datePublished":"2016-07-14T11:55:00+00:00","dateModified":"2021-08-05T11:11:26+00:00","description":"Une partie de l\u2019\u00e9quipe de Puntes s\u2019est rendue \u00e0 Dusseldorf pour visiter la Drupa 2016, le salon mondial de r\u00e9f\u00e9rence des m\u00e9tiers des arts graphiques et industriels de l\u2019imprimerie.","breadcrumb":{"@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puntes.es\/fr\/drupa-2016\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#primaryimage","url":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg","contentUrl":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/drupa-20161-1.jpg","width":700,"height":644},{"@type":"BreadcrumbList","@id":"https:\/\/puntes.es\/fr\/drupa-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puntes.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Drupa 2016"}]},{"@type":"WebSite","@id":"https:\/\/puntes.es\/#website","url":"https:\/\/puntes.es\/","name":"Puntes","description":"Packaging partners","publisher":{"@id":"https:\/\/puntes.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puntes.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/puntes.es\/#organization","name":"Puntes","url":"https:\/\/puntes.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/puntes.es\/#\/schema\/logo\/image\/","url":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/punts.svg","contentUrl":"https:\/\/puntes.es\/wp-content\/uploads\/2021\/05\/punts.svg","width":1,"height":1,"caption":"Puntes"},"image":{"@id":"https:\/\/puntes.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puntes.es\/#\/schema\/person\/4a8046f9f021d0bcd1f32edb26c1b11d","name":"AgenciaESI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff0da8b57ee364cc3b2b7c24e1277377873e5a5fb2bd7e6c6d78819a1d5942c2?s=96&d=mm&r=g","caption":"AgenciaESI"}}]}},"_links":{"self":[{"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/posts\/3021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/comments?post=3021"}],"version-history":[{"count":1,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/posts\/3021\/revisions"}],"predecessor-version":[{"id":3022,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/posts\/3021\/revisions\/3022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/media\/2919"}],"wp:attachment":[{"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/media?parent=3021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/categories?post=3021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puntes.es\/fr\/wp-json\/wp\/v2\/tags?post=3021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}